{"id":16173,"date":"2014-03-16T19:34:12","date_gmt":"2014-03-16T19:34:12","guid":{"rendered":"http:\/\/ourtour.co.uk\/home\/?p=16173"},"modified":"2021-06-20T13:39:01","modified_gmt":"2021-06-20T12:39:01","slug":"hymer-b544-motorhome-for-sale-seeks-new-loving-home","status":"publish","type":"post","link":"https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/","title":{"rendered":"Hymer B544 Motorhome For Sale, Seeks New Loving Home"},"content":{"rendered":"<p>The time&#8217;s come for the Motorhome Formerly Known as Dave to be set free. We realised that he has been on the drive for six months and barely used, so he&#8217;s up for sale, hopefully to someone who can take him off on adventures anew; he&#8217;s chomping at the bit, adventure wagon that he is. We&#8217;re ploughing on with our <strong><a href=\"https:\/\/ourtour.co.uk\/home\/the-money-muppet\/\" target=\"_blank\" rel=\"noopener\">long term aim to hit early retirement<\/a><\/strong> and we need to sell Dave, ah, erm, our B544 motorhome, to get the money invested, sad but true.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/vCAL-hdubpU?rel=0\" width=\"640\" height=\"480\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/XWkqIQyUU1k?rel=0\" width=\"640\" height=\"480\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>If you&#8217;re interested, or know someone who may be, please don&#8217;t hesitate to get in touch. We&#8217;re about 3 miles off J26 of the M1, near IKEA Nottingham (postcode NG16 3NJ), and can be contacted at <strong><a href=\"mailto:julieandjason@ourtour.co.uk\" target=\"_blank\" rel=\"noopener\">julieandjason@ourtour.co.uk<\/a><\/strong>\u00a0or 07860 827 454 to arrange a good time to look over the van and have a chat over a brew. There&#8217;s a bunch of photos below, followed by all the facts we can remember!<\/p>\n<p><a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00355.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16210\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00355-300x225.jpg\" alt=\"DSC00355\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00355-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00355-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00355-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00355-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00354.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16209\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00354-300x225.jpg\" alt=\"DSC00354\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00354-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00354-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00354-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00354-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00353.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16208\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00353-300x225.jpg\" alt=\"DSC00353\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00353-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00353-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00353-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00353-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00352.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16207\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00352-300x225.jpg\" alt=\"DSC00352\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00352-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00352-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00352-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00352-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00351.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16206\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00351-300x225.jpg\" alt=\"DSC00351\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00351-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00351-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00351-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00351-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00350.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16205\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00350-300x117.jpg\" alt=\"DSC00350\" width=\"300\" height=\"117\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00350-300x117.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00350-1024x400.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00349-e1394993543646.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16204\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00349-e1394993543646-225x300.jpg\" alt=\"DSC00349\" width=\"225\" height=\"300\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00349-e1394993543646-225x300.jpg 225w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00349-e1394993543646-768x1024.jpg 768w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00349-e1394993543646.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00348.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16203\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00348-300x225.jpg\" alt=\"DSC00348\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00348-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00348-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00348-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00348-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00347.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16202\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00347-300x117.jpg\" alt=\"DSC00347\" width=\"300\" height=\"117\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00347-300x117.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00347-1024x400.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00345-e1394993662269.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16200\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00345-e1394993662269-225x300.jpg\" alt=\"DSC00345\" width=\"225\" height=\"300\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00345-e1394993662269-225x300.jpg 225w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00345-e1394993662269-768x1024.jpg 768w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00345-e1394993662269.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00343.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16198\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00343-300x225.jpg\" alt=\"DSC00343\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00343-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00343-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00343-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00343-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00342-e1394993441273.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16197\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00342-e1394993441273-117x300.jpg\" alt=\"DSC00342\" width=\"117\" height=\"300\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00342-e1394993441273-117x300.jpg 117w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00342-e1394993441273-400x1024.jpg 400w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00342-e1394993441273.jpg 1001w\" sizes=\"auto, (max-width: 117px) 100vw, 117px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00340.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16195\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00340-300x117.jpg\" alt=\"DSC00340\" width=\"300\" height=\"117\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00340-300x117.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00340-1024x400.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00339-e1394993491273.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16194\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00339-e1394993491273-225x300.jpg\" alt=\"DSC00339\" width=\"225\" height=\"300\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00339-e1394993491273-225x300.jpg 225w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00339-e1394993491273-768x1024.jpg 768w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00339-e1394993491273.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00338.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16193\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00338-300x225.jpg\" alt=\"DSC00338\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00338-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00338-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00338-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00338-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00337.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16192\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00337-300x225.jpg\" alt=\"DSC00337\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00337-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00337-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00337-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00337-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00336-e1394993301332.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16191\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00336-e1394993301332-225x300.jpg\" alt=\"DSC00336\" width=\"225\" height=\"300\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00336-e1394993301332-225x300.jpg 225w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00336-e1394993301332-768x1024.jpg 768w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00336-e1394993301332.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00335-e1394993257934.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16190\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00335-e1394993257934-225x300.jpg\" alt=\"DSC00335\" width=\"225\" height=\"300\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00335-e1394993257934-225x300.jpg 225w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00335-e1394993257934-768x1024.jpg 768w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00335-e1394993257934.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00334.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16189\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00334-300x225.jpg\" alt=\"DSC00334\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00334-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00334-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00334-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00334-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00333-e1394993211496.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16188\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00333-e1394993211496-225x300.jpg\" alt=\"DSC00333\" width=\"225\" height=\"300\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00333-e1394993211496-225x300.jpg 225w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00333-e1394993211496-768x1024.jpg 768w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00333-e1394993211496.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00332-e1394993167213.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16187\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00332-e1394993167213-225x300.jpg\" alt=\"DSC00332\" width=\"225\" height=\"300\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00332-e1394993167213-225x300.jpg 225w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00332-e1394993167213-768x1024.jpg 768w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00332-e1394993167213.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00331.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16186\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00331-300x225.jpg\" alt=\"DSC00331\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00331-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00331-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00331-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00331-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00326.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16181\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00326-300x225.jpg\" alt=\"DSC00326\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00326-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00326-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00326-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00326-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00327.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16182\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00327-300x225.jpg\" alt=\"DSC00327\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00327-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00327-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00327-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00327-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00328.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16183\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00328-300x225.jpg\" alt=\"DSC00328\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00328-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00328-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00328-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00328-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00329-e1394993373848.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16184\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00329-e1394993373848-225x300.jpg\" alt=\"DSC00329\" width=\"225\" height=\"300\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00329-e1394993373848-225x300.jpg 225w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00329-e1394993373848-768x1024.jpg 768w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00329-e1394993373848.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00330.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16185\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00330-300x225.jpg\" alt=\"DSC00330\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00330-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00330-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00330-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00330-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00325.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16180\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00325-300x225.jpg\" alt=\"DSC00325\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00325-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00325-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00325-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00325-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00324.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16179\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00324-300x225.jpg\" alt=\"DSC00324\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00324-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00324-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00324-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00324-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00323.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16178\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00323-300x225.jpg\" alt=\"DSC00323\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00323-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00323-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00323-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00323-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00322.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16177\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00322-300x225.jpg\" alt=\"DSC00322\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00322-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00322-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00322-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00322-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<div id=\"attachment_16174\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00319.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-16174\" class=\"size-medium wp-image-16174\" src=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00319-300x225.jpg\" alt=\"The Hymer B544 Motorhome formerly known as Dave\" width=\"300\" height=\"225\" srcset=\"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00319-300x225.jpg 300w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00319-1024x768.jpg 1024w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00319-174x131.jpg 174w, https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00319-70x53.jpg 70w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-16174\" class=\"wp-caption-text\">The Hymer B544 Motorhome formerly known as Dave<\/p><\/div>\n<p><span style=\"font-size: medium;\"><strong>Key Facts<\/strong><\/span><\/p>\n<ul>\n<li>Asking price: \u00a39500 ono<\/li>\n<li><span style=\"font-size: small;\">First registered in Germany in 1993,\u00a0<\/span><span style=\"font-size: small;\">Imported into the UK in 2002<\/span><\/li>\n<li><span style=\"font-size: small;\">126270 miles (the speedo shows KMs), Full Service History plus operating guides<\/span><\/li>\n<li><span style=\"font-size: small;\">2.5 Non-Turbo Diesel Engine<\/span><\/li>\n<li><span style=\"font-size: small;\">Left Hand Drive, manual, five gears with power steering<\/span><\/li>\n<li><span style=\"font-size: small;\">UK-legal headlights\/rear fog light<\/span><\/li>\n<li>3100 Kg max weight<\/li>\n<li><span style=\"font-size: small;\">MOT to 14 Sep 2014<\/span><\/li>\n<li><span style=\"font-size: small;\">Tax to 31 Aug 2014<\/span><\/li>\n<li>30 litre Refillable LPG tank for heating, water heating, cooking &amp; fridge, with dish and bayonet adapters included<\/li>\n<li>100 litre Fresh and Waste water tanks<\/li>\n<li>100Wp Solar Panel with 12V 100 Ah Leisure Battery<\/li>\n<li>2 Bike Rack<\/li>\n<li>Comfortably sleeps 4, with 2 full belted seats and 4 lap-belted seats<\/li>\n<\/ul>\n<p><strong><span style=\"font-size: medium;\">Kitchen<\/span><\/strong><\/p>\n<ul>\n<li>3 burner hob powered by LPG<\/li>\n<li>3 way Electrolux fridge (12V when engine running, or LPG\/230V hook-up when stationary) with freezer compartment<\/li>\n<li>Sink with hot and cold mixer tap<\/li>\n<li>Air extraction fan and light<\/li>\n<li>Control unit showing status of starter\/leisure battery and fresh\/grey water tanks<\/li>\n<li>Storage and bin<\/li>\n<\/ul>\n<p><strong><span style=\"font-size: medium;\">Bathroom<\/span><\/strong><\/p>\n<ul>\n<li>Wet-room style<\/li>\n<li>Thetford cassette chemical toilet<\/li>\n<li>Mixer tap which also acts as ceiling-mountable shower head<\/li>\n<li>Panel to allow shower head to be used outside<\/li>\n<li>Mirrored storage unit and under sink storage<\/li>\n<\/ul>\n<p><strong><span style=\"font-size: medium;\">Sleeping<\/span><\/strong><\/p>\n<ul>\n<li>Over-cab drop-down double bed, ladder included (although we never needed it)<\/li>\n<li>Living area also converts into a double and a single, or one very large bed area<\/li>\n<\/ul>\n<p><strong><span style=\"font-size: medium;\">Storage<\/span><\/strong><\/p>\n<ul>\n<li>Eight overhead cupboards<\/li>\n<li>Storage under long bench<\/li>\n<li>Storage under one of the short benches<\/li>\n<li>Wardrobe with removable shelves (hanging rail in place if you don&#8217;t want shelves)<\/li>\n<li>Bathroom and kitchen storage<\/li>\n<li>Storage under passenger seat<\/li>\n<\/ul>\n<p><strong><span style=\"font-size: medium;\">Heating<\/span><\/strong><\/p>\n<ul>\n<li>Truma water heater, powered by LPG<\/li>\n<li>Truma blown air heating, powered by LPG<\/li>\n<li>External Silver Screens for windscreen and two cab side windows<\/li>\n<li>Thermal black-out lining on all curtains<\/li>\n<\/ul>\n<p><strong><span style=\"font-size: medium;\">Lighting<\/span><\/strong><\/p>\n<ul>\n<li>LED lighting strips to both sides of main living area<\/li>\n<li>12V strip light and spot lights in main living area<\/li>\n<li>12V lights in Kitchen and Bathroom<\/li>\n<\/ul>\n<p><strong><span style=\"font-size: medium;\">Power<\/span><\/strong><\/p>\n<ul>\n<li>100Ah 12V leisure battery<\/li>\n<li>Leisure battery charged from alternator when engine running, or from 230V hook-up and\/or 100Wp solar panel mounted on the roof<\/li>\n<li>230V hook-up with EU-style two pin (three pin adapter included) socket in kitchen, and three pin socket in living area.<\/li>\n<li>12v sockets in kitchen, living area &amp; dashboard<\/li>\n<\/ul>\n<p><strong><span style=\"font-size: medium;\">Others<\/span><\/strong><\/p>\n<ul>\n<li>Radio-CD player (plus USB connection) with surround sound, speakers on dashboard and in living area<\/li>\n<li>Analogue TV aerial<\/li>\n<li>Flat panel TV mounting bracket<\/li>\n<li>Air-assisted suspension fitted<\/li>\n<li>Removable carpets to main living space<\/li>\n<li>Additional security lock fitted to exterior of habitation door, interior of habitation door and drivers door<\/li>\n<li>Manual lever for drop-down step to habitation door<\/li>\n<\/ul>\n<p>If you&#8217;ve any questions, please don&#8217;t hesitate to ask, thanks! Jason and Julie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The time&#8217;s come for the Motorhome Formerly Known as Dave to be set free. We realised that he has been on the drive for six months and barely used, so he&#8217;s up for sale, hopefully to someone who can take him off on adventures anew; he&#8217;s chomping at the bit, adventure wagon that he is. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16210,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[417,1528,415],"tags":[],"class_list":["post-16173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-motorhome-blog","category-our-motorhomes","category-at-home"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hymer B544 Motorhome For Sale, Seeks New Loving Home - Our Tour Motorhome Blog<\/title>\n<meta name=\"description\" content=\"With our future plans keeping us in the UK for a while, we sadly need to say goodbye to Dave. Our Hymer B544 motorhome is for sale (NOW SOLD)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hymer B544 Motorhome For Sale, Seeks New Loving Home - Our Tour Motorhome Blog\" \/>\n<meta property=\"og:description\" content=\"With our future plans keeping us in the UK for a while, we sadly need to say goodbye to Dave. Our Hymer B544 motorhome is for sale (NOW SOLD)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/\" \/>\n<meta property=\"og:site_name\" content=\"Our Tour Motorhome Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OurTour\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-16T19:34:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-20T12:39:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ourtour.co.uk\/home\/wp-content\/uploads\/2014\/03\/DSC00355-1024x768.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jason\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ourtourblog\" \/>\n<meta name=\"twitter:site\" content=\"@ourtourblog\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jason\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\\\/\"},\"author\":{\"name\":\"Jason\",\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/#\\\/schema\\\/person\\\/28b4763ac800fdf951974d671ed33d28\"},\"headline\":\"Hymer B544 Motorhome For Sale, Seeks New Loving Home\",\"datePublished\":\"2014-03-16T19:34:12+00:00\",\"dateModified\":\"2021-06-20T12:39:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\\\/\"},\"wordCount\":613,\"commentCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ourtourmedia.s3.eu-central-003.backblazeb2.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/DSC00355.jpg\",\"articleSection\":[\"Blog\",\"Our Motorhomes\",\"While at Home\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\\\/\",\"url\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\\\/\",\"name\":\"Hymer B544 Motorhome For Sale, Seeks New Loving Home - Our Tour Motorhome Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ourtourmedia.s3.eu-central-003.backblazeb2.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/DSC00355.jpg\",\"datePublished\":\"2014-03-16T19:34:12+00:00\",\"dateModified\":\"2021-06-20T12:39:01+00:00\",\"description\":\"With our future plans keeping us in the UK for a while, we sadly need to say goodbye to Dave. Our Hymer B544 motorhome is for sale (NOW SOLD)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ourtourmedia.s3.eu-central-003.backblazeb2.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/DSC00355.jpg\",\"contentUrl\":\"https:\\\/\\\/ourtourmedia.s3.eu-central-003.backblazeb2.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/DSC00355.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hymer B544 Motorhome For Sale, Seeks New Loving Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/\",\"name\":\"Our Tour Motorhome Blog\",\"description\":\"Touring Europe and Beyond by Motorhome\",\"publisher\":{\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/#organization\",\"name\":\"The OurTour Motorhome Travel Blog\",\"url\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/OurTour-Logo-Square-no-Strapline-small.jpg\",\"contentUrl\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/OurTour-Logo-Square-no-Strapline-small.jpg\",\"width\":300,\"height\":206,\"caption\":\"The OurTour Motorhome Travel Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OurTour\\\/\",\"https:\\\/\\\/x.com\\\/ourtourblog\",\"https:\\\/\\\/www.instagram.com\\\/ourtourblog\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKAWyrFnDzaZ5xJxCWHskmQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ourtour.co.uk\\\/home\\\/#\\\/schema\\\/person\\\/28b4763ac800fdf951974d671ed33d28\",\"name\":\"Jason\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hymer B544 Motorhome For Sale, Seeks New Loving Home - Our Tour Motorhome Blog","description":"With our future plans keeping us in the UK for a while, we sadly need to say goodbye to Dave. Our Hymer B544 motorhome is for sale (NOW SOLD)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/","og_locale":"en_GB","og_type":"article","og_title":"Hymer B544 Motorhome For Sale, Seeks New Loving Home - Our Tour Motorhome Blog","og_description":"With our future plans keeping us in the UK for a while, we sadly need to say goodbye to Dave. Our Hymer B544 motorhome is for sale (NOW SOLD)","og_url":"https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/","og_site_name":"Our Tour Motorhome Blog","article_publisher":"https:\/\/www.facebook.com\/OurTour\/","article_published_time":"2014-03-16T19:34:12+00:00","article_modified_time":"2021-06-20T12:39:01+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/ourtour.co.uk\/home\/wp-content\/uploads\/2014\/03\/DSC00355-1024x768.jpg","type":"image\/jpeg"}],"author":"Jason","twitter_card":"summary_large_image","twitter_creator":"@ourtourblog","twitter_site":"@ourtourblog","twitter_misc":{"Written by":"Jason","Estimated reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/#article","isPartOf":{"@id":"https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/"},"author":{"name":"Jason","@id":"https:\/\/ourtour.co.uk\/home\/#\/schema\/person\/28b4763ac800fdf951974d671ed33d28"},"headline":"Hymer B544 Motorhome For Sale, Seeks New Loving Home","datePublished":"2014-03-16T19:34:12+00:00","dateModified":"2021-06-20T12:39:01+00:00","mainEntityOfPage":{"@id":"https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/"},"wordCount":613,"commentCount":10,"publisher":{"@id":"https:\/\/ourtour.co.uk\/home\/#organization"},"image":{"@id":"https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/#primaryimage"},"thumbnailUrl":"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00355.jpg","articleSection":["Blog","Our Motorhomes","While at Home"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/","url":"https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/","name":"Hymer B544 Motorhome For Sale, Seeks New Loving Home - Our Tour Motorhome Blog","isPartOf":{"@id":"https:\/\/ourtour.co.uk\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/#primaryimage"},"image":{"@id":"https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/#primaryimage"},"thumbnailUrl":"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00355.jpg","datePublished":"2014-03-16T19:34:12+00:00","dateModified":"2021-06-20T12:39:01+00:00","description":"With our future plans keeping us in the UK for a while, we sadly need to say goodbye to Dave. Our Hymer B544 motorhome is for sale (NOW SOLD)","breadcrumb":{"@id":"https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/#primaryimage","url":"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00355.jpg","contentUrl":"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00355.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/ourtour.co.uk\/home\/hymer-b544-motorhome-for-sale-seeks-new-loving-home\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ourtour.co.uk\/home\/"},{"@type":"ListItem","position":2,"name":"Hymer B544 Motorhome For Sale, Seeks New Loving Home"}]},{"@type":"WebSite","@id":"https:\/\/ourtour.co.uk\/home\/#website","url":"https:\/\/ourtour.co.uk\/home\/","name":"Our Tour Motorhome Blog","description":"Touring Europe and Beyond by Motorhome","publisher":{"@id":"https:\/\/ourtour.co.uk\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ourtour.co.uk\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/ourtour.co.uk\/home\/#organization","name":"The OurTour Motorhome Travel Blog","url":"https:\/\/ourtour.co.uk\/home\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ourtour.co.uk\/home\/#\/schema\/logo\/image\/","url":"https:\/\/ourtour.co.uk\/home\/wp-content\/uploads\/2018\/12\/OurTour-Logo-Square-no-Strapline-small.jpg","contentUrl":"https:\/\/ourtour.co.uk\/home\/wp-content\/uploads\/2018\/12\/OurTour-Logo-Square-no-Strapline-small.jpg","width":300,"height":206,"caption":"The OurTour Motorhome Travel Blog"},"image":{"@id":"https:\/\/ourtour.co.uk\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OurTour\/","https:\/\/x.com\/ourtourblog","https:\/\/www.instagram.com\/ourtourblog\/","https:\/\/www.youtube.com\/channel\/UCKAWyrFnDzaZ5xJxCWHskmQ"]},{"@type":"Person","@id":"https:\/\/ourtour.co.uk\/home\/#\/schema\/person\/28b4763ac800fdf951974d671ed33d28","name":"Jason"}]}},"jetpack_featured_media_url":"https:\/\/ourtourmedia.s3.eu-central-003.backblazeb2.com\/wp-content\/uploads\/2014\/03\/DSC00355.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ourtour.co.uk\/home\/wp-json\/wp\/v2\/posts\/16173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ourtour.co.uk\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ourtour.co.uk\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ourtour.co.uk\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ourtour.co.uk\/home\/wp-json\/wp\/v2\/comments?post=16173"}],"version-history":[{"count":11,"href":"https:\/\/ourtour.co.uk\/home\/wp-json\/wp\/v2\/posts\/16173\/revisions"}],"predecessor-version":[{"id":41367,"href":"https:\/\/ourtour.co.uk\/home\/wp-json\/wp\/v2\/posts\/16173\/revisions\/41367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ourtour.co.uk\/home\/wp-json\/wp\/v2\/media\/16210"}],"wp:attachment":[{"href":"https:\/\/ourtour.co.uk\/home\/wp-json\/wp\/v2\/media?parent=16173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ourtour.co.uk\/home\/wp-json\/wp\/v2\/categories?post=16173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ourtour.co.uk\/home\/wp-json\/wp\/v2\/tags?post=16173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}